{"id":134,"date":"2015-12-05T18:38:51","date_gmt":"2015-12-05T17:38:51","guid":{"rendered":"http:\/\/margauxathome.com\/wp-content\/uploads\/2015\/11\/plateau-fromages.jpeg"},"modified":"2015-12-05T18:38:51","modified_gmt":"2015-12-05T17:38:51","slug":"plateau-fromages","status":"inherit","type":"attachment","link":"https:\/\/ateliermargaux.fr\/index.php\/premier-panneau\/plateau-fromages\/","title":{"rendered":"plateau fromages"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-134","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a data-title=\"plateau fromages\" data-alt=\"\" href='https:\/\/ateliermargaux.fr\/wp-content\/uploads\/2015\/11\/plateau-fromages.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/ateliermargaux.fr\/wp-content\/uploads\/2015\/11\/plateau-fromages-300x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/ateliermargaux.fr\/wp-content\/uploads\/2015\/11\/plateau-fromages-300x300.jpeg 300w, https:\/\/ateliermargaux.fr\/wp-content\/uploads\/2015\/11\/plateau-fromages-150x150.jpeg 150w, https:\/\/ateliermargaux.fr\/wp-content\/uploads\/2015\/11\/plateau-fromages-900x900.jpeg 900w, https:\/\/ateliermargaux.fr\/wp-content\/uploads\/2015\/11\/plateau-fromages-400x400.jpeg 400w, https:\/\/ateliermargaux.fr\/wp-content\/uploads\/2015\/11\/plateau-fromages.jpeg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":960,"height":960,"file":"2015\/11\/plateau-fromages.jpeg","sizes":{"thumbnail":{"file":"plateau-fromages-150x150.jpeg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/ateliermargaux.fr\/wp-content\/uploads\/2015\/11\/plateau-fromages-150x150.jpeg"},"medium":{"file":"plateau-fromages-300x300.jpeg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/ateliermargaux.fr\/wp-content\/uploads\/2015\/11\/plateau-fromages-300x300.jpeg"},"medium-size":{"file":"plateau-fromages-900x900.jpeg","width":900,"height":900,"mime_type":"image\/jpeg","source_url":"https:\/\/ateliermargaux.fr\/wp-content\/uploads\/2015\/11\/plateau-fromages-900x900.jpeg"},"small-size":{"file":"plateau-fromages-400x400.jpeg","width":400,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/ateliermargaux.fr\/wp-content\/uploads\/2015\/11\/plateau-fromages-400x400.jpeg"},"full":{"file":"plateau-fromages.jpeg","width":960,"height":960,"mime_type":"image\/jpeg","source_url":"https:\/\/ateliermargaux.fr\/wp-content\/uploads\/2015\/11\/plateau-fromages.jpeg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0}},"post":8,"source_url":"https:\/\/ateliermargaux.fr\/wp-content\/uploads\/2015\/11\/plateau-fromages.jpeg","_links":{"self":[{"href":"https:\/\/ateliermargaux.fr\/index.php\/wp-json\/wp\/v2\/media\/134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ateliermargaux.fr\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/ateliermargaux.fr\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/ateliermargaux.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ateliermargaux.fr\/index.php\/wp-json\/wp\/v2\/comments?post=134"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":8,"href":"https:\/\/ateliermargaux.fr\/index.php\/wp-json\/wp\/v2\/pages\/8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}